{"id":1706,"date":"2024-03-15T08:46:59","date_gmt":"2024-03-15T07:46:59","guid":{"rendered":"https:\/\/frigofernelmont.abako.be\/contact\/"},"modified":"2024-10-31T11:48:21","modified_gmt":"2024-10-31T10:48:21","slug":"contact","status":"publish","type":"page","link":"https:\/\/www.frigofernelmont.be\/fr\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1706\" class=\"elementor elementor-1706 elementor-555\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9d30154 e-flex e-con-boxed e-con e-parent\" data-id=\"9d30154\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;curve&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n    <path class=\"elementor-shape-fill\" d=\"M1000,4.3V0H0v4.3C0.9,23.1,126.7,99.2,500,100S1000,22.7,1000,4.3z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-76b9fe8 e-flex e-con-boxed e-con e-parent\" data-id=\"76b9fe8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-af7c9ad e-con-full e-flex e-con e-child\" data-id=\"af7c9ad\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a0b5ff3 elementor-widget elementor-widget-heading\" data-id=\"a0b5ff3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CONTACT<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-42f603c e-con-full e-flex e-con e-child\" data-id=\"42f603c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-8aad51e e-con-full e-flex e-con e-child\" data-id=\"8aad51e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-8d8a1a6 e-flex e-con-boxed e-con e-child\" data-id=\"8d8a1a6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-055528d elementor-widget elementor-widget-text-editor\" data-id=\"055528d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><em><span style=\"color: #1e769c; font-size: 20px; font-weight: 900;\">FRIGO FERNELMONT<\/span><\/em><\/p><p>Rue du Grand Champ 9<\/p><p>Noville-Les-Bois<\/p><p>B-5380 FERNELMONT<\/p><p>T (+32) 081 \/ 830 550<\/p><p>Email: <span style=\"text-decoration: underline;\"><span style=\"color: #000000;\"><a style=\"color: #000000; text-decoration: underline;\" href=\"mailto:info@frigofernelmont.be\">info@frigofernelmont.be<\/a><\/span><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-73c7fd9 e-flex e-con-boxed e-con e-child\" data-id=\"73c7fd9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-69b0b8c elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"69b0b8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"398\" height=\"398\" src=\"https:\/\/www.frigofernelmont.be\/wp-content\/uploads\/2024\/10\/22.png\" class=\"attachment-full size-full wp-image-2372\" alt=\"\" srcset=\"https:\/\/www.frigofernelmont.be\/wp-content\/uploads\/2024\/10\/22.png 398w, https:\/\/www.frigofernelmont.be\/wp-content\/uploads\/2024\/10\/22-300x300.png 300w, https:\/\/www.frigofernelmont.be\/wp-content\/uploads\/2024\/10\/22-150x150.png 150w\" sizes=\"(max-width: 398px) 100vw, 398px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2968448 e-flex e-con-boxed e-con e-child\" data-id=\"2968448\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4997378 elementor-widget elementor-widget-shortcode\" data-id=\"4997378\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"forminator-ui forminator-custom-form forminator-custom-form-1756 forminator-design--default  forminator_ajax\" data-forminator-render=\"0\" data-form=\"forminator-module-1756\" data-uid=\"6a97ab7d102e1\"><br\/><\/div><form\n\t\t\t\tid=\"forminator-module-1756\"\n\t\t\t\tclass=\"forminator-ui forminator-custom-form forminator-custom-form-1756 forminator-design--default  forminator_ajax\"\n\t\t\t\tmethod=\"post\"\n\t\t\t\tdata-forminator-render=\"0\"\n\t\t\t\tdata-form-id=\"1756\"\n\t\t\t\t data-color-option=\"default\" data-design=\"default\" data-grid=\"open\" style=\"display: none;\"\n\t\t\t\tdata-uid=\"6a97ab7d102e1\"\n\t\t\t><div role=\"alert\" aria-live=\"polite\" class=\"forminator-response-message forminator-error\" aria-hidden=\"true\"><\/div><div class=\"forminator-row\"><div id=\"name-1\" class=\"forminator-field-name forminator-col forminator-col-6  contactform-field\"><div class=\"forminator-field\"><input type=\"text\" name=\"name-1\" value=\"\" placeholder=\"Pr\u00e9nom\" id=\"forminator-field-name-1_6a97ab7d102e1\" class=\"forminator-input forminator-name--field\" aria-required=\"true\" autocomplete=\"name\" \/><\/div><\/div><div id=\"name-2\" class=\"forminator-field-name forminator-col forminator-col-6  contactform-field\"><div class=\"forminator-field\"><input type=\"text\" name=\"name-2\" value=\"\" placeholder=\"Nom de famille\" id=\"forminator-field-name-2_6a97ab7d102e1\" class=\"forminator-input forminator-name--field\" aria-required=\"true\" autocomplete=\"name\" \/><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"email-1\" class=\"forminator-field-email forminator-col forminator-col-12  contactform-field\"><div class=\"forminator-field\"><input type=\"email\" name=\"email-1\" value=\"\" placeholder=\"E-mail\" id=\"forminator-field-email-1_6a97ab7d102e1\" class=\"forminator-input forminator-email--field\" data-required=\"1\" aria-required=\"true\" autocomplete=\"email\" \/><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"address-1\" class=\"forminator-field-address forminator-col forminator-col-12  contactform-field\"><div class=\"forminator-row\"><div id=\"address-1-street_address\" class=\"forminator-col\"><div class=\"forminator-field\"><input type=\"text\" name=\"address-1-street_address\" placeholder=\"Rue + Num\u00e9ro\" id=\"forminator-field-address-1-street_address_6a97ab7d102e1\" class=\"forminator-input\" data-required=\"1\" aria-required=\"true\" autocomplete=\"address-line1\" value=\"\" \/><\/div><\/div><\/div><div class=\"forminator-row\" data-multiple=\"true\"><div id=\"address-1-city\" class=\"forminator-col forminator-col-6\"><div class=\"forminator-field\"><input type=\"text\" name=\"address-1-city\" placeholder=\"Ville\" id=\"forminator-field-address-1-city_6a97ab7d102e1\" class=\"forminator-input\" data-required=\"1\" aria-required=\"true\" autocomplete=\"address-level2\" value=\"\" \/><\/div><\/div><div id=\"address-1-state\" class=\"forminator-col forminator-col-6\"><div class=\"forminator-field\"><input type=\"text\" name=\"address-1-state\" placeholder=\"Province\" id=\"forminator-field-address-1-state_6a97ab7d102e1\" class=\"forminator-input\" data-required=\"1\" aria-required=\"true\" autocomplete=\"address-level1\" value=\"\" \/><\/div><\/div><\/div><div class=\"forminator-row\" data-multiple=\"true\"><div id=\"address-1-zip\" class=\"forminator-col forminator-col-6\"><div class=\"forminator-field\"><input type=\"text\" name=\"address-1-zip\" placeholder=\"Code Postal\" id=\"forminator-field-address-1-zip_6a97ab7d102e1\" class=\"forminator-input\" autocomplete=\"postal-code\" value=\"\" \/><\/div><\/div><div id=\"address-1-country\" class=\"forminator-col forminator-col-6\"><div class=\"forminator-field\"><select name=\"address-1-country\" id=\"forminator-field-1756__field--address-1-country_6a97ab7d102e1\" class=\"forminator-select2\" data-search=\"true\" data-placeholder=\"S\u00e9lectionner un pays\" autocomplete=\"country-name\" data-default-value=\"Belgi\u00eb\"><option value=\"\" data-country-code=\"\" selected=\"selected\"><\/option><option value=\"Afghanistan\" data-country-code=\"AF\" >Afghanistan<\/option><option value=\"Afrique du Sud\" data-country-code=\"ZA\" >Afrique du Sud<\/option><option value=\"Albanie\" data-country-code=\"AL\" >Albanie<\/option><option value=\"Alg\u00e9rie\" data-country-code=\"DZ\" >Alg\u00e9rie<\/option><option value=\"Allemagne\" data-country-code=\"DE\" >Allemagne<\/option><option value=\"Andorre\" data-country-code=\"AD\" >Andorre<\/option><option value=\"Angola\" data-country-code=\"AO\" >Angola<\/option><option value=\"Anguilla\" data-country-code=\"AI\" >Anguilla<\/option><option value=\"Antarctique\" data-country-code=\"AQ\" >Antarctique<\/option><option value=\"Antigua &amp; Barbuda\" data-country-code=\"AG\" >Antigua &amp; Barbuda<\/option><option value=\"Arabie Saoudite\" data-country-code=\"SA\" >Arabie Saoudite<\/option><option value=\"Argentine\" data-country-code=\"AR\" >Argentine<\/option><option value=\"Arm\u00e9nie\" data-country-code=\"AM\" >Arm\u00e9nie<\/option><option value=\"Aruba\" data-country-code=\"AW\" >Aruba<\/option><option value=\"Ascension Island\" data-country-code=\"AC\" >Ascension Island<\/option><option value=\"Australie\" data-country-code=\"AU\" >Australie<\/option><option value=\"Autriche\" data-country-code=\"AT\" >Autriche<\/option><option value=\"Azerba\u00efdjan\" data-country-code=\"AZ\" >Azerba\u00efdjan<\/option><option value=\"Bahamas\" data-country-code=\"BS\" >Bahamas<\/option><option value=\"Bahre\u00efn\" data-country-code=\"BH\" >Bahre\u00efn<\/option><option value=\"Bangladesh\" data-country-code=\"BD\" >Bangladesh<\/option><option value=\"Belgique\" data-country-code=\"BE\" >Belgique<\/option><option value=\"Bermudes\" data-country-code=\"BM\" >Bermudes<\/option><option value=\"Bhoutan\" data-country-code=\"BT\" >Bhoutan<\/option><option value=\"Bi\u00e9lorussie\" data-country-code=\"BY\" >Bi\u00e9lorussie<\/option><option value=\"Bolivie\" data-country-code=\"BO\" >Bolivie<\/option><option value=\"Bosnie-Herz\u00e9govine\" data-country-code=\"BA\" >Bosnie-Herz\u00e9govine<\/option><option value=\"Botswana\" data-country-code=\"BW\" >Botswana<\/option><option value=\"British Virgin Islands\" data-country-code=\"VG\" >British Virgin Islands<\/option><option value=\"Brunei\" data-country-code=\"BN\" >Brunei<\/option><option value=\"Br\u00e9sil\" data-country-code=\"BR\" >Br\u00e9sil<\/option><option value=\"Bulgarie\" data-country-code=\"BG\" >Bulgarie<\/option><option value=\"Burkina Faso\" data-country-code=\"BF\" >Burkina Faso<\/option><option value=\"Burundi\" data-country-code=\"BI\" >Burundi<\/option><option value=\"B\u00e9lize\" data-country-code=\"BZ\" >B\u00e9lize<\/option><option value=\"B\u00e9nin\" data-country-code=\"BJ\" >B\u00e9nin<\/option><option value=\"Cambodge\" data-country-code=\"KH\" >Cambodge<\/option><option value=\"Cameroun\" data-country-code=\"CM\" >Cameroun<\/option><option value=\"Canada\" data-country-code=\"CA\" >Canada<\/option><option value=\"Cap Vert\" data-country-code=\"CV\" >Cap Vert<\/option><option value=\"Caribbean Netherlands\" data-country-code=\"BQ\" >Caribbean Netherlands<\/option><option value=\"Chili\" data-country-code=\"CL\" >Chili<\/option><option value=\"China\" data-country-code=\"CN\" >China<\/option><option value=\"Chypre\" data-country-code=\"CY\" >Chypre<\/option><option value=\"Cit\u00e9 du Vatican\" data-country-code=\"VA\" >Cit\u00e9 du Vatican<\/option><option value=\"Colombie\" data-country-code=\"CO\" >Colombie<\/option><option value=\"Comores\" data-country-code=\"KM\" >Comores<\/option><option value=\"Congo, R\u00e9publique du\" data-country-code=\"CG\" >Congo, R\u00e9publique du<\/option><option value=\"Congo, R\u00e9publique d\u00e9mocratique du\" data-country-code=\"CD\" >Congo, R\u00e9publique d\u00e9mocratique du<\/option><option value=\"Costa Rica\" data-country-code=\"CR\" >Costa Rica<\/option><option value=\"Croatie\" data-country-code=\"HR\" >Croatie<\/option><option value=\"Cuba\" data-country-code=\"CU\" >Cuba<\/option><option value=\"Cura\u00e7ao\" data-country-code=\"CW\" >Cura\u00e7ao<\/option><option value=\"Czechia\" data-country-code=\"CZ\" >Czechia<\/option><option value=\"C\u00f4te d\u2019Ivoire\" data-country-code=\"CI\" >C\u00f4te d\u2019Ivoire<\/option><option value=\"Danemark\" data-country-code=\"DK\" >Danemark<\/option><option value=\"Djibouti\" data-country-code=\"DJ\" >Djibouti<\/option><option value=\"Dominique\" data-country-code=\"DM\" >Dominique<\/option><option value=\"Espagne\" data-country-code=\"ES\" >Espagne<\/option><option value=\"Estonie\" data-country-code=\"EE\" >Estonie<\/option><option value=\"Eswatini\" data-country-code=\"SZ\" >Eswatini<\/option><option value=\"Fidji\" data-country-code=\"FJ\" >Fidji<\/option><option value=\"Finlande\" data-country-code=\"FI\" >Finlande<\/option><option value=\"France\" data-country-code=\"FR\" >France<\/option><option value=\"Gabon\" data-country-code=\"GA\" >Gabon<\/option><option value=\"Gambie\" data-country-code=\"GM\" >Gambie<\/option><option value=\"Ghana\" data-country-code=\"GH\" >Ghana<\/option><option value=\"Gibraltar\" data-country-code=\"GI\" >Gibraltar<\/option><option value=\"Grenade\" data-country-code=\"GD\" >Grenade<\/option><option value=\"Groenland\" data-country-code=\"GL\" >Groenland<\/option><option value=\"Gr\u00e8ce\" data-country-code=\"GR\" >Gr\u00e8ce<\/option><option value=\"Guadeloupe\" data-country-code=\"GP\" >Guadeloupe<\/option><option value=\"Guam\" data-country-code=\"GU\" >Guam<\/option><option value=\"Guat\u00e9mala\" data-country-code=\"GT\" >Guat\u00e9mala<\/option><option value=\"Guernesey\" data-country-code=\"GG\" >Guernesey<\/option><option value=\"Guin\u00e9e\" data-country-code=\"GN\" >Guin\u00e9e<\/option><option value=\"Guin\u00e9e \u00c9quatoriale\" data-country-code=\"GQ\" >Guin\u00e9e \u00c9quatoriale<\/option><option value=\"Guin\u00e9e-Bissau\" data-country-code=\"GW\" >Guin\u00e9e-Bissau<\/option><option value=\"Guyane\" data-country-code=\"GY\" >Guyane<\/option><option value=\"Guyane fran\u00e7aise\" data-country-code=\"GF\" >Guyane fran\u00e7aise<\/option><option value=\"G\u00e9orgie\" data-country-code=\"GE\" >G\u00e9orgie<\/option><option value=\"G\u00e9orgie du Sud et Sandwich du Sud\" data-country-code=\"GS\" >G\u00e9orgie du Sud et Sandwich du Sud<\/option><option value=\"Ha\u00efti\" data-country-code=\"HT\" >Ha\u00efti<\/option><option value=\"Honduras\" data-country-code=\"HN\" >Honduras<\/option><option value=\"Hong Kong SAR China\" data-country-code=\"HK\" >Hong Kong SAR China<\/option><option value=\"Hongrie\" data-country-code=\"HU\" >Hongrie<\/option><option value=\"Inde\" data-country-code=\"IN\" >Inde<\/option><option value=\"Indon\u00e9sie\" data-country-code=\"ID\" >Indon\u00e9sie<\/option><option value=\"Iran\" data-country-code=\"IR\" >Iran<\/option><option value=\"Iraq\" data-country-code=\"IQ\" >Iraq<\/option><option value=\"Irlande\" data-country-code=\"IE\" >Irlande<\/option><option value=\"Islande\" data-country-code=\"IS\" >Islande<\/option><option value=\"Isle of Man\" data-country-code=\"IM\" >Isle of Man<\/option><option value=\"Israel\" data-country-code=\"IL\" >Israel<\/option><option value=\"Italie\" data-country-code=\"IT\" >Italie<\/option><option value=\"Jama\u00efque\" data-country-code=\"JM\" >Jama\u00efque<\/option><option value=\"Japon\" data-country-code=\"JP\" >Japon<\/option><option value=\"Jersey\" data-country-code=\"JE\" >Jersey<\/option><option value=\"Jordanie\" data-country-code=\"JO\" >Jordanie<\/option><option value=\"Kazakhstan\" data-country-code=\"KZ\" >Kazakhstan<\/option><option value=\"Kenya\" data-country-code=\"KE\" >Kenya<\/option><option value=\"Kirghizistan\" data-country-code=\"KG\" >Kirghizistan<\/option><option value=\"Kiribati\" data-country-code=\"KI\" >Kiribati<\/option><option value=\"Kosovo\" data-country-code=\"XK\" >Kosovo<\/option><option value=\"Kowe\u00eft\" data-country-code=\"KW\" >Kowe\u00eft<\/option><option value=\"La Barbade\" data-country-code=\"BB\" >La Barbade<\/option><option value=\"Lesotho\" data-country-code=\"LS\" >Lesotho<\/option><option value=\"Lettonie\" data-country-code=\"LV\" >Lettonie<\/option><option value=\"Liban\" data-country-code=\"LB\" >Liban<\/option><option value=\"Libye\" data-country-code=\"LY\" >Libye<\/option><option value=\"Lib\u00e9ria\" data-country-code=\"LR\" >Lib\u00e9ria<\/option><option value=\"Liechtenstein\" data-country-code=\"LI\" >Liechtenstein<\/option><option value=\"Lithuanie\" data-country-code=\"LT\" >Lithuanie<\/option><option value=\"Luxembourg\" data-country-code=\"LU\" >Luxembourg<\/option><option value=\"Macao SAR China\" data-country-code=\"MO\" >Macao SAR China<\/option><option value=\"Mac\u00e9doine du Nord\" data-country-code=\"MK\" >Mac\u00e9doine du Nord<\/option><option value=\"Madagascar\" data-country-code=\"MG\" >Madagascar<\/option><option value=\"Malaisie\" data-country-code=\"MY\" >Malaisie<\/option><option value=\"Malawi\" data-country-code=\"MW\" >Malawi<\/option><option value=\"Maldives\" data-country-code=\"MV\" >Maldives<\/option><option value=\"Mali\" data-country-code=\"ML\" >Mali<\/option><option value=\"Malte\" data-country-code=\"MT\" >Malte<\/option><option value=\"Maroc\" data-country-code=\"MA\" >Maroc<\/option><option value=\"Martinique\" data-country-code=\"MQ\" >Martinique<\/option><option value=\"Mauritanie\" data-country-code=\"MR\" >Mauritanie<\/option><option value=\"Mayotte\" data-country-code=\"YT\" >Mayotte<\/option><option value=\"Mexique\" data-country-code=\"MX\" >Mexique<\/option><option value=\"Micron\u00e9sie\" data-country-code=\"FM\" >Micron\u00e9sie<\/option><option value=\"Moldavie\" data-country-code=\"MD\" >Moldavie<\/option><option value=\"Monaco\" data-country-code=\"MC\" >Monaco<\/option><option value=\"Mongolie\" data-country-code=\"MN\" >Mongolie<\/option><option value=\"Montserrat\" data-country-code=\"MS\" >Montserrat<\/option><option value=\"Mont\u00e9n\u00e9gro\" data-country-code=\"ME\" >Mont\u00e9n\u00e9gro<\/option><option value=\"Mozambique\" data-country-code=\"MZ\" >Mozambique<\/option><option value=\"Myanmar\" data-country-code=\"MM\" >Myanmar<\/option><option value=\"Namibie\" data-country-code=\"NA\" >Namibie<\/option><option value=\"Nauru\" data-country-code=\"NR\" >Nauru<\/option><option value=\"Nicaragua\" data-country-code=\"NI\" >Nicaragua<\/option><option value=\"Niger\" data-country-code=\"NE\" >Niger<\/option><option value=\"Nig\u00e9ria\" data-country-code=\"NG\" >Nig\u00e9ria<\/option><option value=\"Niu\u00e9\" data-country-code=\"NU\" >Niu\u00e9<\/option><option value=\"North Korea\" data-country-code=\"KP\" >North Korea<\/option><option value=\"Norv\u00e8ge\" data-country-code=\"NO\" >Norv\u00e8ge<\/option><option value=\"Nouvelle Zelande\" data-country-code=\"NZ\" >Nouvelle Zelande<\/option><option value=\"Nouvelle-Cal\u00e9donie\" data-country-code=\"NC\" >Nouvelle-Cal\u00e9donie<\/option><option value=\"N\u00e9pal\" data-country-code=\"NP\" >N\u00e9pal<\/option><option value=\"Oman\" data-country-code=\"OM\" >Oman<\/option><option value=\"Ouganda\" data-country-code=\"UG\" >Ouganda<\/option><option value=\"Ouzb\u00e9kistan\" data-country-code=\"UZ\" >Ouzb\u00e9kistan<\/option><option value=\"Pakistan\" data-country-code=\"PK\" >Pakistan<\/option><option value=\"Palau\" data-country-code=\"PW\" >Palau<\/option><option value=\"Palestinian Territories\" data-country-code=\"PS\" >Palestinian Territories<\/option><option value=\"Panama\" data-country-code=\"PA\" >Panama<\/option><option value=\"Papouasie-Nouvelle-Guin\u00e9e\" data-country-code=\"PG\" >Papouasie-Nouvelle-Guin\u00e9e<\/option><option value=\"Paraguay\" data-country-code=\"PY\" >Paraguay<\/option><option value=\"Pays-Bas\" data-country-code=\"NL\" >Pays-Bas<\/option><option value=\"Philippines\" data-country-code=\"PH\" >Philippines<\/option><option value=\"Pologne\" data-country-code=\"PL\" >Pologne<\/option><option value=\"Polyn\u00e9sie Fran\u00e7aise\" data-country-code=\"PF\" >Polyn\u00e9sie Fran\u00e7aise<\/option><option value=\"Porto Rico\" data-country-code=\"PR\" >Porto Rico<\/option><option value=\"Portugal\" data-country-code=\"PT\" >Portugal<\/option><option value=\"P\u00e9rou\" data-country-code=\"PE\" >P\u00e9rou<\/option><option value=\"Qatar\" data-country-code=\"QA\" >Qatar<\/option><option value=\"Roumanie\" data-country-code=\"RO\" >Roumanie<\/option><option value=\"Royaume-Uni\" data-country-code=\"GB\" >Royaume-Uni<\/option><option value=\"Russie\" data-country-code=\"RU\" >Russie<\/option><option value=\"Rwanda\" data-country-code=\"RW\" >Rwanda<\/option><option value=\"R\u00e9publique Centrafricaine\" data-country-code=\"CF\" >R\u00e9publique Centrafricaine<\/option><option value=\"R\u00e9publique Dominicaine\" data-country-code=\"DO\" >R\u00e9publique Dominicaine<\/option><option value=\"R\u00e9publique du Salvador\" data-country-code=\"SV\" >R\u00e9publique du Salvador<\/option><option value=\"R\u00e9publique d\u00e9mocratique populaire du Laos\" data-country-code=\"LA\" >R\u00e9publique d\u00e9mocratique populaire du Laos<\/option><option value=\"R\u00e9union\" data-country-code=\"RE\" >R\u00e9union<\/option><option value=\"Sahara occidental\" data-country-code=\"EH\" >Sahara occidental<\/option><option value=\"Saint-Kitts-et-Nevis\" data-country-code=\"KN\" >Saint-Kitts-et-Nevis<\/option><option value=\"Saint-Marin\" data-country-code=\"SM\" >Saint-Marin<\/option><option value=\"Saint-Martin (Royaume des Pays-Bas)\" data-country-code=\"SX\" >Saint-Martin (Royaume des Pays-Bas)<\/option><option value=\"Saint-Vincent-et-les-Grenadines\" data-country-code=\"VC\" >Saint-Vincent-et-les-Grenadines<\/option><option value=\"Sainte-H\u00e9l\u00e8ne\" data-country-code=\"SH\" >Sainte-H\u00e9l\u00e8ne<\/option><option value=\"Sainte-Lucie\" data-country-code=\"LC\" >Sainte-Lucie<\/option><option value=\"Samoa\" data-country-code=\"WS\" >Samoa<\/option><option value=\"Samoa am\u00e9ricaines\" data-country-code=\"AS\" >Samoa am\u00e9ricaines<\/option><option value=\"Serbie\" data-country-code=\"RS\" >Serbie<\/option><option value=\"Seychelles\" data-country-code=\"SC\" >Seychelles<\/option><option value=\"Sierra Leone\" data-country-code=\"SL\" >Sierra Leone<\/option><option value=\"Singapour\" data-country-code=\"SG\" >Singapour<\/option><option value=\"Slovaquie\" data-country-code=\"SK\" >Slovaquie<\/option><option value=\"Slov\u00e9nie\" data-country-code=\"SI\" >Slov\u00e9nie<\/option><option value=\"Somalie\" data-country-code=\"SO\" >Somalie<\/option><option value=\"Soudan\" data-country-code=\"SD\" >Soudan<\/option><option value=\"South Korea\" data-country-code=\"KR\" >South Korea<\/option><option value=\"South Sudan\" data-country-code=\"SS\" >South Sudan<\/option><option value=\"Sri Lanka\" data-country-code=\"LK\" >Sri Lanka<\/option><option value=\"St. Barth\u00e9lemy\" data-country-code=\"BL\" >St. Barth\u00e9lemy<\/option><option value=\"St. Martin\" data-country-code=\"MF\" >St. Martin<\/option><option value=\"St. Pierre &amp; Miquelon\" data-country-code=\"PM\" >St. Pierre &amp; Miquelon<\/option><option value=\"Suisse\" data-country-code=\"CH\" >Suisse<\/option><option value=\"Suriname\" data-country-code=\"SR\" >Suriname<\/option><option value=\"Su\u00e8de\" data-country-code=\"SE\" >Su\u00e8de<\/option><option value=\"Svalbard et Jan Mayen\" data-country-code=\"SJ\" >Svalbard et Jan Mayen<\/option><option value=\"Syrie\" data-country-code=\"SY\" >Syrie<\/option><option value=\"S\u00e3o Tom\u00e9 &amp; Pr\u00edncipe\" data-country-code=\"ST\" >S\u00e3o Tom\u00e9 &amp; Pr\u00edncipe<\/option><option value=\"S\u00e9n\u00e9gal\" data-country-code=\"SN\" >S\u00e9n\u00e9gal<\/option><option value=\"Tadjikistan\" data-country-code=\"TJ\" >Tadjikistan<\/option><option value=\"Taiwan\" data-country-code=\"TW\" >Taiwan<\/option><option value=\"Tanzanie\" data-country-code=\"TZ\" >Tanzanie<\/option><option value=\"Tchad\" data-country-code=\"TD\" >Tchad<\/option><option value=\"Terres australes et antarctiques fran\u00e7aises\" data-country-code=\"TF\" >Terres australes et antarctiques fran\u00e7aises<\/option><option value=\"Territoire britannique de l\u2019oc\u00e9an Indien\" data-country-code=\"IO\" >Territoire britannique de l\u2019oc\u00e9an Indien<\/option><option value=\"Tha\u00eflande\" data-country-code=\"TH\" >Tha\u00eflande<\/option><option value=\"Timor-Leste\" data-country-code=\"TL\" >Timor-Leste<\/option><option value=\"Togo\" data-country-code=\"TG\" >Togo<\/option><option value=\"Tokelau\" data-country-code=\"TK\" >Tokelau<\/option><option value=\"Tonga\" data-country-code=\"TO\" >Tonga<\/option><option value=\"Trinidad &amp; Tobago\" data-country-code=\"TT\" >Trinidad &amp; Tobago<\/option><option value=\"Tunisie\" data-country-code=\"TN\" >Tunisie<\/option><option value=\"Turkm\u00e9nistan\" data-country-code=\"TM\" >Turkm\u00e9nistan<\/option><option value=\"Turks &amp; Caicos Islands\" data-country-code=\"TC\" >Turks &amp; Caicos Islands<\/option><option value=\"Turquie\" data-country-code=\"TR\" >Turquie<\/option><option value=\"Tuvalu\" data-country-code=\"TV\" >Tuvalu<\/option><option value=\"U.S. Virgin Islands\" data-country-code=\"VI\" >U.S. Virgin Islands<\/option><option value=\"Ukraine\" data-country-code=\"UA\" >Ukraine<\/option><option value=\"Uruguay\" data-country-code=\"UY\" >Uruguay<\/option><option value=\"Vanuatu\" data-country-code=\"VU\" >Vanuatu<\/option><option value=\"Vietnam\" data-country-code=\"VN\" >Vietnam<\/option><option value=\"V\u00e9n\u00e9zu\u00e9la\" data-country-code=\"VE\" >V\u00e9n\u00e9zu\u00e9la<\/option><option value=\"Yemen\" data-country-code=\"YE\" >Yemen<\/option><option value=\"Zambie\" data-country-code=\"ZM\" >Zambie<\/option><option value=\"Zimbabwe\" data-country-code=\"ZW\" >Zimbabwe<\/option><option value=\"\u00c9gypte\" data-country-code=\"EG\" >\u00c9gypte<\/option><option value=\"\u00c9mirats Arabes Unis\" data-country-code=\"AE\" >\u00c9mirats Arabes Unis<\/option><option value=\"\u00c9quateur\" data-country-code=\"EC\" >\u00c9quateur<\/option><option value=\"\u00c9rythr\u00e9e\" data-country-code=\"ER\" >\u00c9rythr\u00e9e<\/option><option value=\"\u00c9tats-Unis d\u2019Am\u00e9rique (USA)\" data-country-code=\"US\" >\u00c9tats-Unis d\u2019Am\u00e9rique (USA)<\/option><option value=\"\u00c9thiopie\" data-country-code=\"ET\" >\u00c9thiopie<\/option><option value=\"\u00cele Bouvet\" data-country-code=\"BV\" >\u00cele Bouvet<\/option><option value=\"\u00cele Christmas\" data-country-code=\"CX\" >\u00cele Christmas<\/option><option value=\"\u00cele Heard et \u00eele Mcdonald\" data-country-code=\"HM\" >\u00cele Heard et \u00eele Mcdonald<\/option><option value=\"\u00cele Maurice\" data-country-code=\"MU\" >\u00cele Maurice<\/option><option value=\"\u00cele Norfolk\" data-country-code=\"NF\" >\u00cele Norfolk<\/option><option value=\"\u00celes Ca\u00efmans\" data-country-code=\"KY\" >\u00celes Ca\u00efmans<\/option><option value=\"\u00celes Cocos\" data-country-code=\"CC\" >\u00celes Cocos<\/option><option value=\"\u00celes Cook\" data-country-code=\"CK\" >\u00celes Cook<\/option><option value=\"\u00celes Falkland\" data-country-code=\"FK\" >\u00celes Falkland<\/option><option value=\"\u00celes F\u00e9ro\u00e9\" data-country-code=\"FO\" >\u00celes F\u00e9ro\u00e9<\/option><option value=\"\u00celes Mariannes du Nord\" data-country-code=\"MP\" >\u00celes Mariannes du Nord<\/option><option value=\"\u00celes Marshall\" data-country-code=\"MH\" >\u00celes Marshall<\/option><option value=\"\u00celes Pitcairn\" data-country-code=\"PN\" >\u00celes Pitcairn<\/option><option value=\"\u00celes Salomon\" data-country-code=\"SB\" >\u00celes Salomon<\/option><option value=\"\u00celes Wallis et Futuna\" data-country-code=\"WF\" >\u00celes Wallis et Futuna<\/option><option value=\"\u00celes mineures \u00e9loign\u00e9es des \u00c9tats-Unis\" data-country-code=\"UM\" >\u00celes mineures \u00e9loign\u00e9es des \u00c9tats-Unis<\/option><\/select><\/div><\/div><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"textarea-1\" class=\"forminator-field-textarea forminator-col forminator-col-12  contactform-field\"><div class=\"forminator-field\"><textarea name=\"textarea-1\" placeholder=\"Votre message\/question\" id=\"forminator-field-textarea-1_6a97ab7d102e1\" class=\"forminator-textarea\" style=\"--forminator-textarea-min-height:140px;\" ><\/textarea><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"captcha-1\" class=\"forminator-field-captcha forminator-col forminator-col-12 \"><div class=\"forminator-captcha-left forminator-g-recaptcha recaptcha-invisible\" data-theme=\"light\" data-badge=\"inline\" data-sitekey=\"6LeDgm8qAAAAAFudK9b6xpnjttUi7bfgkH10FQV8\" data-size=\"invisible\"><\/div> <\/div><\/div><input type=\"hidden\" name=\"referer_url\" value=\"\" \/><div class=\"forminator-row forminator-row-last\"><div class=\"forminator-col\"><div class=\"forminator-field\"><button class=\"forminator-button forminator-button-submit\">Envoyer<\/button><\/div><\/div><\/div><input type=\"hidden\" id=\"forminator_nonce\" name=\"forminator_nonce\" value=\"c11ab65f38\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/fr\/wp-json\/wp\/v2\/pages\/1706\" \/><input type=\"hidden\" name=\"form_id\" value=\"1756\"><input type=\"hidden\" name=\"page_id\" value=\"1706\"><input type=\"hidden\" name=\"form_type\" value=\"default\"><input type=\"hidden\" name=\"current_url\" value=\"https:\/\/www.frigofernelmont.be\/fr\/contact\/\"><input type=\"hidden\" name=\"render_id\" value=\"0\"><input type=\"hidden\" name=\"action\" value=\"forminator_submit_form_custom-forms\"><\/form><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>CONTACT FRIGO FERNELMONT Rue du Grand Champ 9 Noville-Les-Bois B-5380 FERNELMONT T (+32) 081 \/ 830 550 Email: info@frigofernelmont.be<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1706","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contact - Frigo Fernelmont<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.frigofernelmont.be\/fr\/contact\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contact - Frigo Fernelmont\" \/>\n<meta property=\"og:description\" content=\"CONTACT FRIGO FERNELMONT Rue du Grand Champ 9 Noville-Les-Bois B-5380 FERNELMONT T (+32) 081 \/ 830 550 Email: info@frigofernelmont.be\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.frigofernelmont.be\/fr\/contact\/\" \/>\n<meta property=\"og:site_name\" content=\"Frigo Fernelmont\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-31T10:48:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.frigofernelmont.be\/wp-content\/uploads\/2024\/10\/22.png\" \/>\n\t<meta property=\"og:image:width\" content=\"398\" \/>\n\t<meta property=\"og:image:height\" content=\"398\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.frigofernelmont.be\\\/fr\\\/contact\\\/\",\"url\":\"https:\\\/\\\/www.frigofernelmont.be\\\/fr\\\/contact\\\/\",\"name\":\"Contact - Frigo Fernelmont\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.frigofernelmont.be\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.frigofernelmont.be\\\/fr\\\/contact\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.frigofernelmont.be\\\/fr\\\/contact\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.frigofernelmont.be\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/22.png\",\"datePublished\":\"2024-03-15T07:46:59+00:00\",\"dateModified\":\"2024-10-31T10:48:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.frigofernelmont.be\\\/fr\\\/contact\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.frigofernelmont.be\\\/fr\\\/contact\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.frigofernelmont.be\\\/fr\\\/contact\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.frigofernelmont.be\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/22.png\",\"contentUrl\":\"https:\\\/\\\/www.frigofernelmont.be\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/22.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.frigofernelmont.be\\\/fr\\\/contact\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.frigofernelmont.be\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contact\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.frigofernelmont.be\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.frigofernelmont.be\\\/fr\\\/\",\"name\":\"Frigo Fernelmont\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.frigofernelmont.be\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.frigofernelmont.be\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.frigofernelmont.be\\\/fr\\\/#organization\",\"name\":\"Frigo Fernelmont\",\"url\":\"https:\\\/\\\/www.frigofernelmont.be\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.frigofernelmont.be\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.frigofernelmont.be\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.frigofernelmont.be\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo.png\",\"width\":315,\"height\":100,\"caption\":\"Frigo Fernelmont\"},\"image\":{\"@id\":\"https:\\\/\\\/www.frigofernelmont.be\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contact - Frigo Fernelmont","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.frigofernelmont.be\/fr\/contact\/","og_locale":"fr_FR","og_type":"article","og_title":"Contact - Frigo Fernelmont","og_description":"CONTACT FRIGO FERNELMONT Rue du Grand Champ 9 Noville-Les-Bois B-5380 FERNELMONT T (+32) 081 \/ 830 550 Email: info@frigofernelmont.be","og_url":"https:\/\/www.frigofernelmont.be\/fr\/contact\/","og_site_name":"Frigo Fernelmont","article_modified_time":"2024-10-31T10:48:21+00:00","og_image":[{"width":398,"height":398,"url":"https:\/\/www.frigofernelmont.be\/wp-content\/uploads\/2024\/10\/22.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.frigofernelmont.be\/fr\/contact\/","url":"https:\/\/www.frigofernelmont.be\/fr\/contact\/","name":"Contact - Frigo Fernelmont","isPartOf":{"@id":"https:\/\/www.frigofernelmont.be\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.frigofernelmont.be\/fr\/contact\/#primaryimage"},"image":{"@id":"https:\/\/www.frigofernelmont.be\/fr\/contact\/#primaryimage"},"thumbnailUrl":"https:\/\/www.frigofernelmont.be\/wp-content\/uploads\/2024\/10\/22.png","datePublished":"2024-03-15T07:46:59+00:00","dateModified":"2024-10-31T10:48:21+00:00","breadcrumb":{"@id":"https:\/\/www.frigofernelmont.be\/fr\/contact\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.frigofernelmont.be\/fr\/contact\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.frigofernelmont.be\/fr\/contact\/#primaryimage","url":"https:\/\/www.frigofernelmont.be\/wp-content\/uploads\/2024\/10\/22.png","contentUrl":"https:\/\/www.frigofernelmont.be\/wp-content\/uploads\/2024\/10\/22.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.frigofernelmont.be\/fr\/contact\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.frigofernelmont.be\/fr\/"},{"@type":"ListItem","position":2,"name":"Contact"}]},{"@type":"WebSite","@id":"https:\/\/www.frigofernelmont.be\/fr\/#website","url":"https:\/\/www.frigofernelmont.be\/fr\/","name":"Frigo Fernelmont","description":"","publisher":{"@id":"https:\/\/www.frigofernelmont.be\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.frigofernelmont.be\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.frigofernelmont.be\/fr\/#organization","name":"Frigo Fernelmont","url":"https:\/\/www.frigofernelmont.be\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.frigofernelmont.be\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.frigofernelmont.be\/wp-content\/uploads\/2022\/07\/logo.png","contentUrl":"https:\/\/www.frigofernelmont.be\/wp-content\/uploads\/2022\/07\/logo.png","width":315,"height":100,"caption":"Frigo Fernelmont"},"image":{"@id":"https:\/\/www.frigofernelmont.be\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.frigofernelmont.be\/fr\/wp-json\/wp\/v2\/pages\/1706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.frigofernelmont.be\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.frigofernelmont.be\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.frigofernelmont.be\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.frigofernelmont.be\/fr\/wp-json\/wp\/v2\/comments?post=1706"}],"version-history":[{"count":0,"href":"https:\/\/www.frigofernelmont.be\/fr\/wp-json\/wp\/v2\/pages\/1706\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.frigofernelmont.be\/fr\/wp-json\/wp\/v2\/media?parent=1706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}